{"id":36145,"date":"2023-05-04T15:19:28","date_gmt":"2023-05-04T19:19:28","guid":{"rendered":"https:\/\/www.premrawat.com\/reprise-transmissao-e-arrecadacao-de-fundos-da-wopg-para-apoiar-os-eventos-de-prem-rawat\/"},"modified":"2023-05-13T06:45:42","modified_gmt":"2023-05-13T10:45:42","slug":"reprise-transmissao-e-arrecadacao-de-fundos-da-wopg-para-apoiar-os-eventos-de-prem-rawat","status":"publish","type":"post","link":"https:\/\/www.premrawat.com\/pt-br\/reprise-transmissao-e-arrecadacao-de-fundos-da-wopg-para-apoiar-os-eventos-de-prem-rawat\/","title":{"rendered":"REPRISE: Transmiss\u00e3o e arrecada\u00e7\u00e3o de fundos da WOPG para apoiar os eventos de Prem Rawat"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.20.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_row _builder_version=&#8221;4.20.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.20.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; link_text_color=&#8221;#1565b7&#8243; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p>Words of Peace Global (WOPG) desempenha um papel crucial em tornar poss\u00edveis os eventos de Prem Rawat em todo o mundo, e este m\u00eas a funda\u00e7\u00e3o beneficente est\u00e1 buscando seu apoio. Como parte de seu esfor\u00e7o de arrecada\u00e7\u00e3o de fundos \u201cVamos nos Preparar \u2013 2023\u201d, os principais membros da equipe WOPG apareceram recentemente em uma transmiss\u00e3o para atualiz\u00e1-lo sobre as \u00faltimas not\u00edcias sobre as atividades de Prem Rawat, incluindo sua atual visita \u00e0 \u00c1frica do Sul. Eles tamb\u00e9m compartilharam alguns momentos fascinantes dos bastidores relacionados aos eventos recentes de\u00a0Lucknow\u00a0e\u00a0<a href=\"about:blank\">Ilhas Maur\u00edcio<\/a><\/p>\n<p style=\"text-align: center;\"><b>A reprise desta transmiss\u00e3o da WOPG de 29 de Abril\u00a0<\/b><b>estar\u00e1 dispon\u00edvel sob demanda at\u00e9 22 de Maio.<\/b><\/p>\n<p style=\"text-align: center;\"><a href=\"about:blank\"><b>Assista a Reprise da Transmiss\u00e3o Aqui<\/b><\/a><\/p>\n<p style=\"text-align: center;\"><a href=\"about:blank\"><b>Doa\u00e7\u00f5es para WOPG Aqui<\/b><\/a><\/p>\n<p>Palestrantes em destaque:<\/p>\n<ul>\n<li>Hilary Davis, Gerente de Eventos Globais<\/li>\n<li>Paul Bloomfield, Diretor Global de Rela\u00e7\u00f5es P\u00fablicas&gt;<\/li>\n<li>Juniali Negi, Diretora de Eventos Globais<\/li>\n<li>Michael Hatjiyannis, Equipe da Sess\u00e3o de Conhecimento Global<\/li>\n<li>Barbara Brogan, Presidente, Words of Peace International<\/li>\n<li>Roland Klepzig, Presidente, Words of Peace Global<\/li>\n<\/ul>\n<p>Haver\u00e1 tradu\u00e7\u00e3o simult\u00e2nea para Franc\u00eas, Espanhol, Alem\u00e3o, Italiano, Portugu\u00eas, Mandarim, T\u00e2mil, Grego e Hindi.<\/p>\n<p>Para obter assist\u00eancia, entre em contato com o helpdesk da Words of Peace:<a href=\"about:blank\">helpdesk@wopg.org<\/a><\/p>\n<p>Contribui\u00e7\u00f5es WOPG recebidas at\u00e9 o momento: $ 115.215. A arrecada\u00e7\u00e3o de fundos continuar\u00e1 nas pr\u00f3ximas semanas.<br \/>:\u00a0Words of Peace (Global)\u00a0\u00e9 uma funda\u00e7\u00e3o beneficente\u00a0 internacional inspirada no trabalho do embaixador internacional da paz\u00a0Prem Rawat. Ele compartilha sua convic\u00e7\u00e3o de que a paz \u00e9 uma necessidade humana fundamental e apoia os esfor\u00e7os para compartilhar sua mensagem em todo o mundo<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Words of Peace Global (WOPG) desempenha um papel crucial em tornar poss\u00edveis os eventos de Prem Rawat em todo o mundo, e este m\u00eas a funda\u00e7\u00e3o beneficente est\u00e1 buscando seu apoio<\/p>\n","protected":false},"author":15,"featured_media":11563,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[4020,4041,3790,4081,4080],"tags":[],"podcast-category":[],"class_list":["post-36145","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigos-de-multimedia","category-envolva-se-pt-br","category-eventos","category-multimidia","category-participar"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>REPRISE: Transmiss\u00e3o e arrecada\u00e7\u00e3o de fundos da WOPG para apoiar os eventos de Prem Rawat - Prem Rawat<\/title>\n<meta name=\"description\" content=\"Words of Peace Global (WOPG) desempenha um papel crucial em tornar poss\u00edveis os eventos de Prem Rawat em todo o mundo, e este m\u00eas a funda\u00e7\u00e3o beneficente est\u00e1 buscando seu apoio\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.premrawat.com\/pt-br\/reprise-transmissao-e-arrecadacao-de-fundos-da-wopg-para-apoiar-os-eventos-de-prem-rawat\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"REPRISE: Transmiss\u00e3o e arrecada\u00e7\u00e3o de fundos da WOPG para apoiar os eventos de Prem Rawat - Prem Rawat\" \/>\n<meta property=\"og:description\" content=\"Words of Peace Global (WOPG) desempenha um papel crucial em tornar poss\u00edveis os eventos de Prem Rawat em todo o mundo, e este m\u00eas a funda\u00e7\u00e3o beneficente est\u00e1 buscando seu apoio\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.premrawat.com\/pt-br\/reprise-transmissao-e-arrecadacao-de-fundos-da-wopg-para-apoiar-os-eventos-de-prem-rawat\/\" \/>\n<meta property=\"og:site_name\" content=\"Prem Rawat\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-04T19:19:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-13T10:45:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.premrawat.com\/2022\/11\/pt-br\/wopg-hands.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1363\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jake Frankel\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jake Frankel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.premrawat.com\\\/pt-br\\\/reprise-transmissao-e-arrecadacao-de-fundos-da-wopg-para-apoiar-os-eventos-de-prem-rawat\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.premrawat.com\\\/pt-br\\\/reprise-transmissao-e-arrecadacao-de-fundos-da-wopg-para-apoiar-os-eventos-de-prem-rawat\\\/\"},\"author\":{\"name\":\"Jake Frankel\",\"@id\":\"https:\\\/\\\/www.premrawat.com\\\/pt-br\\\/#\\\/schema\\\/person\\\/18fb515e3e7f4cec20038b72066a0f23\"},\"headline\":\"REPRISE: Transmiss\u00e3o e arrecada\u00e7\u00e3o de fundos da WOPG para apoiar os eventos de Prem Rawat\",\"datePublished\":\"2023-05-04T19:19:28+00:00\",\"dateModified\":\"2023-05-13T10:45:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.premrawat.com\\\/pt-br\\\/reprise-transmissao-e-arrecadacao-de-fundos-da-wopg-para-apoiar-os-eventos-de-prem-rawat\\\/\"},\"wordCount\":381,\"publisher\":{\"@id\":\"https:\\\/\\\/www.premrawat.com\\\/pt-br\\\/#\\\/schema\\\/person\\\/234f1ca85ac8cb14fc5188673e05c0b1\"},\"image\":{\"@id\":\"https:\\\/\\\/www.premrawat.com\\\/pt-br\\\/reprise-transmissao-e-arrecadacao-de-fundos-da-wopg-para-apoiar-os-eventos-de-prem-rawat\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.premrawat.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/wopg-hands.jpg\",\"articleSection\":[\"Artigos de Multim\u00eddia.\",\"Envolva-se\",\"Eventos\",\"Multim\u00eddia\",\"Participar\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.premrawat.com\\\/pt-br\\\/reprise-transmissao-e-arrecadacao-de-fundos-da-wopg-para-apoiar-os-eventos-de-prem-rawat\\\/\",\"url\":\"https:\\\/\\\/www.premrawat.com\\\/pt-br\\\/reprise-transmissao-e-arrecadacao-de-fundos-da-wopg-para-apoiar-os-eventos-de-prem-rawat\\\/\",\"name\":\"REPRISE: Transmiss\u00e3o e arrecada\u00e7\u00e3o de fundos da WOPG para apoiar os eventos de Prem Rawat - Prem Rawat\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.premrawat.com\\\/pt-br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.premrawat.com\\\/pt-br\\\/reprise-transmissao-e-arrecadacao-de-fundos-da-wopg-para-apoiar-os-eventos-de-prem-rawat\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.premrawat.com\\\/pt-br\\\/reprise-transmissao-e-arrecadacao-de-fundos-da-wopg-para-apoiar-os-eventos-de-prem-rawat\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.premrawat.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/wopg-hands.jpg\",\"datePublished\":\"2023-05-04T19:19:28+00:00\",\"dateModified\":\"2023-05-13T10:45:42+00:00\",\"description\":\"Words of Peace Global (WOPG) desempenha um papel crucial em tornar poss\u00edveis os eventos de Prem Rawat em todo o mundo, e este m\u00eas a funda\u00e7\u00e3o beneficente est\u00e1 buscando seu apoio\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.premrawat.com\\\/pt-br\\\/reprise-transmissao-e-arrecadacao-de-fundos-da-wopg-para-apoiar-os-eventos-de-prem-rawat\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.premrawat.com\\\/pt-br\\\/reprise-transmissao-e-arrecadacao-de-fundos-da-wopg-para-apoiar-os-eventos-de-prem-rawat\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.premrawat.com\\\/pt-br\\\/reprise-transmissao-e-arrecadacao-de-fundos-da-wopg-para-apoiar-os-eventos-de-prem-rawat\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.premrawat.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/wopg-hands.jpg\",\"contentUrl\":\"https:\\\/\\\/www.premrawat.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/wopg-hands.jpg\",\"width\":1363,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.premrawat.com\\\/pt-br\\\/reprise-transmissao-e-arrecadacao-de-fundos-da-wopg-para-apoiar-os-eventos-de-prem-rawat\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.premrawat.com\\\/pt-br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"REPRISE: Transmiss\u00e3o e arrecada\u00e7\u00e3o de fundos da WOPG para apoiar os eventos de Prem Rawat\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.premrawat.com\\\/pt-br\\\/#website\",\"url\":\"https:\\\/\\\/www.premrawat.com\\\/pt-br\\\/\",\"name\":\"Prem Rawat\",\"description\":\"Peace Educator and Best Selling Author\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.premrawat.com\\\/pt-br\\\/#\\\/schema\\\/person\\\/234f1ca85ac8cb14fc5188673e05c0b1\"},\"alternateName\":\"Premrawat.com\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.premrawat.com\\\/pt-br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.premrawat.com\\\/pt-br\\\/#\\\/schema\\\/person\\\/234f1ca85ac8cb14fc5188673e05c0b1\",\"name\":\"Premrawat.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.premrawat.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/prem-rawat-color-logo1.jpg\",\"url\":\"https:\\\/\\\/www.premrawat.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/prem-rawat-color-logo1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.premrawat.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/prem-rawat-color-logo1.jpg\",\"width\":201,\"height\":202,\"caption\":\"Premrawat.com\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.premrawat.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/prem-rawat-color-logo1.jpg\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.premrawat.com\\\/pt-br\\\/#\\\/schema\\\/person\\\/18fb515e3e7f4cec20038b72066a0f23\",\"name\":\"Jake Frankel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8071264e4d7c534df62c63d3b269683cf135a1c0ee27e8e7c34bd713865c4ba2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8071264e4d7c534df62c63d3b269683cf135a1c0ee27e8e7c34bd713865c4ba2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8071264e4d7c534df62c63d3b269683cf135a1c0ee27e8e7c34bd713865c4ba2?s=96&d=mm&r=g\",\"caption\":\"Jake Frankel\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"REPRISE: Transmiss\u00e3o e arrecada\u00e7\u00e3o de fundos da WOPG para apoiar os eventos de Prem Rawat - Prem Rawat","description":"Words of Peace Global (WOPG) desempenha um papel crucial em tornar poss\u00edveis os eventos de Prem Rawat em todo o mundo, e este m\u00eas a funda\u00e7\u00e3o beneficente est\u00e1 buscando seu apoio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.premrawat.com\/pt-br\/reprise-transmissao-e-arrecadacao-de-fundos-da-wopg-para-apoiar-os-eventos-de-prem-rawat\/","og_locale":"pt_BR","og_type":"article","og_title":"REPRISE: Transmiss\u00e3o e arrecada\u00e7\u00e3o de fundos da WOPG para apoiar os eventos de Prem Rawat - Prem Rawat","og_description":"Words of Peace Global (WOPG) desempenha um papel crucial em tornar poss\u00edveis os eventos de Prem Rawat em todo o mundo, e este m\u00eas a funda\u00e7\u00e3o beneficente est\u00e1 buscando seu apoio","og_url":"https:\/\/www.premrawat.com\/pt-br\/reprise-transmissao-e-arrecadacao-de-fundos-da-wopg-para-apoiar-os-eventos-de-prem-rawat\/","og_site_name":"Prem Rawat","article_published_time":"2023-05-04T19:19:28+00:00","article_modified_time":"2023-05-13T10:45:42+00:00","og_image":[{"width":1363,"height":1080,"url":"https:\/\/cdn.premrawat.com\/2022\/11\/pt-br\/wopg-hands.jpg","type":"image\/jpeg"}],"author":"Jake Frankel","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Jake Frankel","Est. tempo de leitura":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.premrawat.com\/pt-br\/reprise-transmissao-e-arrecadacao-de-fundos-da-wopg-para-apoiar-os-eventos-de-prem-rawat\/#article","isPartOf":{"@id":"https:\/\/www.premrawat.com\/pt-br\/reprise-transmissao-e-arrecadacao-de-fundos-da-wopg-para-apoiar-os-eventos-de-prem-rawat\/"},"author":{"name":"Jake Frankel","@id":"https:\/\/www.premrawat.com\/pt-br\/#\/schema\/person\/18fb515e3e7f4cec20038b72066a0f23"},"headline":"REPRISE: Transmiss\u00e3o e arrecada\u00e7\u00e3o de fundos da WOPG para apoiar os eventos de Prem Rawat","datePublished":"2023-05-04T19:19:28+00:00","dateModified":"2023-05-13T10:45:42+00:00","mainEntityOfPage":{"@id":"https:\/\/www.premrawat.com\/pt-br\/reprise-transmissao-e-arrecadacao-de-fundos-da-wopg-para-apoiar-os-eventos-de-prem-rawat\/"},"wordCount":381,"publisher":{"@id":"https:\/\/www.premrawat.com\/pt-br\/#\/schema\/person\/234f1ca85ac8cb14fc5188673e05c0b1"},"image":{"@id":"https:\/\/www.premrawat.com\/pt-br\/reprise-transmissao-e-arrecadacao-de-fundos-da-wopg-para-apoiar-os-eventos-de-prem-rawat\/#primaryimage"},"thumbnailUrl":"https:\/\/www.premrawat.com\/wp-content\/uploads\/2022\/11\/wopg-hands.jpg","articleSection":["Artigos de Multim\u00eddia.","Envolva-se","Eventos","Multim\u00eddia","Participar"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.premrawat.com\/pt-br\/reprise-transmissao-e-arrecadacao-de-fundos-da-wopg-para-apoiar-os-eventos-de-prem-rawat\/","url":"https:\/\/www.premrawat.com\/pt-br\/reprise-transmissao-e-arrecadacao-de-fundos-da-wopg-para-apoiar-os-eventos-de-prem-rawat\/","name":"REPRISE: Transmiss\u00e3o e arrecada\u00e7\u00e3o de fundos da WOPG para apoiar os eventos de Prem Rawat - Prem Rawat","isPartOf":{"@id":"https:\/\/www.premrawat.com\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.premrawat.com\/pt-br\/reprise-transmissao-e-arrecadacao-de-fundos-da-wopg-para-apoiar-os-eventos-de-prem-rawat\/#primaryimage"},"image":{"@id":"https:\/\/www.premrawat.com\/pt-br\/reprise-transmissao-e-arrecadacao-de-fundos-da-wopg-para-apoiar-os-eventos-de-prem-rawat\/#primaryimage"},"thumbnailUrl":"https:\/\/www.premrawat.com\/wp-content\/uploads\/2022\/11\/wopg-hands.jpg","datePublished":"2023-05-04T19:19:28+00:00","dateModified":"2023-05-13T10:45:42+00:00","description":"Words of Peace Global (WOPG) desempenha um papel crucial em tornar poss\u00edveis os eventos de Prem Rawat em todo o mundo, e este m\u00eas a funda\u00e7\u00e3o beneficente est\u00e1 buscando seu apoio","breadcrumb":{"@id":"https:\/\/www.premrawat.com\/pt-br\/reprise-transmissao-e-arrecadacao-de-fundos-da-wopg-para-apoiar-os-eventos-de-prem-rawat\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.premrawat.com\/pt-br\/reprise-transmissao-e-arrecadacao-de-fundos-da-wopg-para-apoiar-os-eventos-de-prem-rawat\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.premrawat.com\/pt-br\/reprise-transmissao-e-arrecadacao-de-fundos-da-wopg-para-apoiar-os-eventos-de-prem-rawat\/#primaryimage","url":"https:\/\/www.premrawat.com\/wp-content\/uploads\/2022\/11\/wopg-hands.jpg","contentUrl":"https:\/\/www.premrawat.com\/wp-content\/uploads\/2022\/11\/wopg-hands.jpg","width":1363,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.premrawat.com\/pt-br\/reprise-transmissao-e-arrecadacao-de-fundos-da-wopg-para-apoiar-os-eventos-de-prem-rawat\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.premrawat.com\/pt-br\/"},{"@type":"ListItem","position":2,"name":"REPRISE: Transmiss\u00e3o e arrecada\u00e7\u00e3o de fundos da WOPG para apoiar os eventos de Prem Rawat"}]},{"@type":"WebSite","@id":"https:\/\/www.premrawat.com\/pt-br\/#website","url":"https:\/\/www.premrawat.com\/pt-br\/","name":"Prem Rawat","description":"Peace Educator and Best Selling Author","publisher":{"@id":"https:\/\/www.premrawat.com\/pt-br\/#\/schema\/person\/234f1ca85ac8cb14fc5188673e05c0b1"},"alternateName":"Premrawat.com","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.premrawat.com\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":["Person","Organization"],"@id":"https:\/\/www.premrawat.com\/pt-br\/#\/schema\/person\/234f1ca85ac8cb14fc5188673e05c0b1","name":"Premrawat.com","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.premrawat.com\/wp-content\/uploads\/2024\/01\/prem-rawat-color-logo1.jpg","url":"https:\/\/www.premrawat.com\/wp-content\/uploads\/2024\/01\/prem-rawat-color-logo1.jpg","contentUrl":"https:\/\/www.premrawat.com\/wp-content\/uploads\/2024\/01\/prem-rawat-color-logo1.jpg","width":201,"height":202,"caption":"Premrawat.com"},"logo":{"@id":"https:\/\/www.premrawat.com\/wp-content\/uploads\/2024\/01\/prem-rawat-color-logo1.jpg"}},{"@type":"Person","@id":"https:\/\/www.premrawat.com\/pt-br\/#\/schema\/person\/18fb515e3e7f4cec20038b72066a0f23","name":"Jake Frankel","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/8071264e4d7c534df62c63d3b269683cf135a1c0ee27e8e7c34bd713865c4ba2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8071264e4d7c534df62c63d3b269683cf135a1c0ee27e8e7c34bd713865c4ba2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8071264e4d7c534df62c63d3b269683cf135a1c0ee27e8e7c34bd713865c4ba2?s=96&d=mm&r=g","caption":"Jake Frankel"}}]}},"_links":{"self":[{"href":"https:\/\/www.premrawat.com\/pt-br\/wp-json\/wp\/v2\/posts\/36145","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.premrawat.com\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.premrawat.com\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.premrawat.com\/pt-br\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/www.premrawat.com\/pt-br\/wp-json\/wp\/v2\/comments?post=36145"}],"version-history":[{"count":11,"href":"https:\/\/www.premrawat.com\/pt-br\/wp-json\/wp\/v2\/posts\/36145\/revisions"}],"predecessor-version":[{"id":36158,"href":"https:\/\/www.premrawat.com\/pt-br\/wp-json\/wp\/v2\/posts\/36145\/revisions\/36158"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.premrawat.com\/pt-br\/wp-json\/wp\/v2\/media\/11563"}],"wp:attachment":[{"href":"https:\/\/www.premrawat.com\/pt-br\/wp-json\/wp\/v2\/media?parent=36145"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.premrawat.com\/pt-br\/wp-json\/wp\/v2\/categories?post=36145"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.premrawat.com\/pt-br\/wp-json\/wp\/v2\/tags?post=36145"},{"taxonomy":"podcast-category","embeddable":true,"href":"https:\/\/www.premrawat.com\/pt-br\/wp-json\/wp\/v2\/podcast-category?post=36145"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}