{"id":48695,"date":"2024-08-02T15:47:04","date_gmt":"2024-08-02T19:47:04","guid":{"rendered":"https:\/\/www.premrawat.com\/il-tour-europeo-2024-di-prem-rawat\/"},"modified":"2024-09-11T11:08:07","modified_gmt":"2024-09-11T15:08:07","slug":"il-tour-europeo-2024-di-prem-rawat","status":"publish","type":"post","link":"https:\/\/www.premrawat.com\/it\/il-tour-europeo-2024-di-prem-rawat\/","title":{"rendered":"Il tour europeo 2024 di Prem Rawat"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;34px|||||&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_row _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;_initial&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.19.3&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_text _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;_initial&#8221; text_font_size=&#8221;20px&#8221; text_line_height=&#8221;1.4em&#8221; link_text_color=&#8221;#1565b7&#8243; custom_margin=&#8221;1px||1px||true|false&#8221; custom_padding=&#8221;0px||0px||true|false&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<p>Nel corso dei mesi di maggio e giugno, Prem Rawat si \u00e8 rivolto a un pubblico riconoscente in cinque citt\u00e0 europee: Dubrovnik in Croazia (19 maggio); Brighton in Inghilterra (8 giugno); Barcellona in Spagna (15 giugno); Roma in Italia (22 giugno) e Atene in Grecia (29 giugno). <\/p>\n<p>Sono intervenute dal vivo pi\u00f9 di 5.500 persone, con oltre 44.000 che hanno assistito alla trasmissione online.<\/p>\n<p>Il tour 2024 \u00e8 stato realizzato grazie al generosissimo sostegno dei donatori, e al lavoro dei volontari locali e dei team organizzatori. <\/p>\n<p>Le repliche di ognuno degli eventi del tour sono disponibili alla visione in varie lingue su TimelessToday\u00ae. Dei brani da essi estratti saranno pubblicati sul canale YouTube ufficiale di Prem Rawat.<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;_initial&#8221; custom_margin=&#8221;30px||||false|false&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<div class=\"epyt-video-wrapper\"><div  id=\"_ytid_47515\"  width=\"1080\" height=\"607\"  data-origwidth=\"1080\" data-origheight=\"607\"  data-relstop=\"1\" data-facadesrc=\"https:\/\/www.youtube.com\/embed\/pgUlyJxaXAA?enablejsapi=1&autoplay=0&cc_load_policy=0&cc_lang_pref=&iv_load_policy=1&loop=0&rel=0&fs=1&playsinline=0&autohide=2&theme=dark&color=red&controls=1&disablekb=0&\" class=\"__youtube_prefs__ epyt-facade no-lazyload\" data-epautoplay=\"1\" ><img decoding=\"async\" data-spai-excluded=\"true\" class=\"epyt-facade-poster skip-lazy\" loading=\"lazy\"  alt=\"YouTube player\"  src=\"https:\/\/i.ytimg.com\/vi\/pgUlyJxaXAA\/maxresdefault.jpg\"  \/><button class=\"epyt-facade-play\" aria-label=\"Play\"><svg data-no-lazy=\"1\" height=\"100%\" version=\"1.1\" viewBox=\"0 0 68 48\" width=\"100%\"><path class=\"ytp-large-play-button-bg\" d=\"M66.52,7.74c-0.78-2.93-2.49-5.41-5.42-6.19C55.79,.13,34,0,34,0S12.21,.13,6.9,1.55 C3.97,2.33,2.27,4.81,1.48,7.74C0.06,13.05,0,24,0,24s0.06,10.95,1.48,16.26c0.78,2.93,2.49,5.41,5.42,6.19 C12.21,47.87,34,48,34,48s21.79-0.13,27.1-1.55c2.93-0.78,4.64-3.26,5.42-6.19C67.94,34.95,68,24,68,24S67.94,13.05,66.52,7.74z\" fill=\"#f00\"><\/path><path d=\"M 45,24 27,14 27,34\" fill=\"#fff\"><\/path><\/svg><\/button><\/div><\/div>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;_initial&#8221; custom_margin=&#8221;50px||50px||true|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<blockquote>\n<h3 style=\"text-align: center;\">Non c\u2019\u00e8 niente di innato in te che ti aiuti a distinguere cosa sia illusorio e cosa non lo sia, e questo ti crea un enorme problema.<\/h3>\n<\/blockquote>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;_initial&#8221; custom_margin=&#8221;-50px||50px||false|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<p style=\"text-align: right;\"><span style=\"font-size: small;\">\u2013 Prem Rawat, 19 maggio 2024, Dubrovnik, Croazia<br \/>\n<\/span><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;_initial&#8221; custom_margin=&#8221;-10px||||false|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<div class=\"epyt-video-wrapper\"><div  id=\"_ytid_96895\"  width=\"1080\" height=\"607\"  data-origwidth=\"1080\" data-origheight=\"607\"  data-relstop=\"1\" data-facadesrc=\"https:\/\/www.youtube.com\/embed\/BYfBdzq-Ofg?enablejsapi=1&autoplay=0&cc_load_policy=0&cc_lang_pref=&iv_load_policy=1&loop=0&rel=0&fs=1&playsinline=0&autohide=2&theme=dark&color=red&controls=1&disablekb=0&\" class=\"__youtube_prefs__ epyt-facade no-lazyload\" data-epautoplay=\"1\" ><img decoding=\"async\" data-spai-excluded=\"true\" class=\"epyt-facade-poster skip-lazy\" loading=\"lazy\"  alt=\"YouTube player\"  src=\"https:\/\/i.ytimg.com\/vi\/BYfBdzq-Ofg\/maxresdefault.jpg\"  \/><button class=\"epyt-facade-play\" aria-label=\"Play\"><svg data-no-lazy=\"1\" height=\"100%\" version=\"1.1\" viewBox=\"0 0 68 48\" width=\"100%\"><path class=\"ytp-large-play-button-bg\" d=\"M66.52,7.74c-0.78-2.93-2.49-5.41-5.42-6.19C55.79,.13,34,0,34,0S12.21,.13,6.9,1.55 C3.97,2.33,2.27,4.81,1.48,7.74C0.06,13.05,0,24,0,24s0.06,10.95,1.48,16.26c0.78,2.93,2.49,5.41,5.42,6.19 C12.21,47.87,34,48,34,48s21.79-0.13,27.1-1.55c2.93-0.78,4.64-3.26,5.42-6.19C67.94,34.95,68,24,68,24S67.94,13.05,66.52,7.74z\" fill=\"#f00\"><\/path><path d=\"M 45,24 27,14 27,34\" fill=\"#fff\"><\/path><\/svg><\/button><\/div><\/div>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;_initial&#8221; custom_margin=&#8221;50px||50px||true|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<blockquote>\n<h3 style=\"text-align: center;\">Cos\u2019\u00e8 la Conoscenza? \u00c8 questo momento meraviglioso per andare in profondit\u00e0 dentro di s\u00e9 a sentire, quando tutto il resto viene lasciato alle spalle, a sentire te stesso. Solo te stesso.<\/h3>\n<\/blockquote>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;_initial&#8221; custom_margin=&#8221;-50px||50px||false|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<p style=\"text-align: right;\"><span style=\"font-size: small;\">Prem Rawat, 8 giugno 2024, Brighton, Inghilterra<br \/>\n<\/span><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;_initial&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<div class=\"epyt-video-wrapper\"><div  id=\"_ytid_93733\"  width=\"1080\" height=\"607\"  data-origwidth=\"1080\" data-origheight=\"607\"  data-relstop=\"1\" data-facadesrc=\"https:\/\/www.youtube.com\/embed\/d-I5BcnIybE?enablejsapi=1&autoplay=0&cc_load_policy=0&cc_lang_pref=&iv_load_policy=1&loop=0&rel=0&fs=1&playsinline=0&autohide=2&theme=dark&color=red&controls=1&disablekb=0&\" class=\"__youtube_prefs__ epyt-facade no-lazyload\" data-epautoplay=\"1\" ><img decoding=\"async\" data-spai-excluded=\"true\" class=\"epyt-facade-poster skip-lazy\" loading=\"lazy\"  alt=\"YouTube player\"  src=\"https:\/\/i.ytimg.com\/vi\/d-I5BcnIybE\/maxresdefault.jpg\"  \/><button class=\"epyt-facade-play\" aria-label=\"Play\"><svg data-no-lazy=\"1\" height=\"100%\" version=\"1.1\" viewBox=\"0 0 68 48\" width=\"100%\"><path class=\"ytp-large-play-button-bg\" d=\"M66.52,7.74c-0.78-2.93-2.49-5.41-5.42-6.19C55.79,.13,34,0,34,0S12.21,.13,6.9,1.55 C3.97,2.33,2.27,4.81,1.48,7.74C0.06,13.05,0,24,0,24s0.06,10.95,1.48,16.26c0.78,2.93,2.49,5.41,5.42,6.19 C12.21,47.87,34,48,34,48s21.79-0.13,27.1-1.55c2.93-0.78,4.64-3.26,5.42-6.19C67.94,34.95,68,24,68,24S67.94,13.05,66.52,7.74z\" fill=\"#f00\"><\/path><path d=\"M 45,24 27,14 27,34\" fill=\"#fff\"><\/path><\/svg><\/button><\/div><\/div>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;_initial&#8221; custom_margin=&#8221;50px||50px||true|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<blockquote>\n<h3 style=\"text-align: center;\">Nella vita non devi fare niente per creare la felicit\u00e0. \u00c8 dentro di te! La felicit\u00e0 pi\u00f9 reale \u00e8 dentro di te. Esiste gi\u00e0.<\/h3>\n<\/blockquote>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;_initial&#8221; custom_margin=&#8221;-50px||50px||false|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<p style=\"text-align: right;\"><span style=\"font-size: small;\">\u2013 Prem Rawat, Barcellona, Spagna, 15 giugno 2024<br \/>\n<\/span><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;_initial&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<div class=\"epyt-video-wrapper\"><div  id=\"_ytid_23776\"  width=\"1080\" height=\"607\"  data-origwidth=\"1080\" data-origheight=\"607\"  data-relstop=\"1\" data-facadesrc=\"https:\/\/www.youtube.com\/embed\/w3GBQruRCyw?enablejsapi=1&autoplay=0&cc_load_policy=0&cc_lang_pref=&iv_load_policy=1&loop=0&rel=0&fs=1&playsinline=0&autohide=2&theme=dark&color=red&controls=1&disablekb=0&\" class=\"__youtube_prefs__ epyt-facade no-lazyload\" data-epautoplay=\"1\" ><img decoding=\"async\" data-spai-excluded=\"true\" class=\"epyt-facade-poster skip-lazy\" loading=\"lazy\"  alt=\"YouTube player\"  src=\"https:\/\/i.ytimg.com\/vi\/w3GBQruRCyw\/maxresdefault.jpg\"  \/><button class=\"epyt-facade-play\" aria-label=\"Play\"><svg data-no-lazy=\"1\" height=\"100%\" version=\"1.1\" viewBox=\"0 0 68 48\" width=\"100%\"><path class=\"ytp-large-play-button-bg\" d=\"M66.52,7.74c-0.78-2.93-2.49-5.41-5.42-6.19C55.79,.13,34,0,34,0S12.21,.13,6.9,1.55 C3.97,2.33,2.27,4.81,1.48,7.74C0.06,13.05,0,24,0,24s0.06,10.95,1.48,16.26c0.78,2.93,2.49,5.41,5.42,6.19 C12.21,47.87,34,48,34,48s21.79-0.13,27.1-1.55c2.93-0.78,4.64-3.26,5.42-6.19C67.94,34.95,68,24,68,24S67.94,13.05,66.52,7.74z\" fill=\"#f00\"><\/path><path d=\"M 45,24 27,14 27,34\" fill=\"#fff\"><\/path><\/svg><\/button><\/div><\/div>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;_initial&#8221; custom_margin=&#8221;50px||50px||true|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<blockquote>\n<h3 style=\"text-align: center;\">\u00c8 il momento che ognuno di noi comprenda l\u2019importanza della pace nella nostra vita. Per avere il coraggio\u2026da dove viene il coraggio? Viene da questioni di cuore.<\/h3>\n<\/blockquote>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;_initial&#8221; custom_margin=&#8221;-50px||50px||false|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<p style=\"text-align: right;\"><span style=\"font-size: small;\">\u2013 Prem Rawat, Roma, Italia, 22 giugno 2024<br \/>\n<\/span><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;_initial&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<div class=\"epyt-video-wrapper\"><div  id=\"_ytid_19082\"  width=\"1080\" height=\"607\"  data-origwidth=\"1080\" data-origheight=\"607\"  data-relstop=\"1\" data-facadesrc=\"https:\/\/www.youtube.com\/embed\/PCZ2RO2M83A?enablejsapi=1&autoplay=0&cc_load_policy=0&cc_lang_pref=&iv_load_policy=1&loop=0&rel=0&fs=1&playsinline=0&autohide=2&theme=dark&color=red&controls=1&disablekb=0&\" class=\"__youtube_prefs__ epyt-facade no-lazyload\" data-epautoplay=\"1\" ><img decoding=\"async\" data-spai-excluded=\"true\" class=\"epyt-facade-poster skip-lazy\" loading=\"lazy\"  alt=\"YouTube player\"  src=\"https:\/\/i.ytimg.com\/vi\/PCZ2RO2M83A\/maxresdefault.jpg\"  \/><button class=\"epyt-facade-play\" aria-label=\"Play\"><svg data-no-lazy=\"1\" height=\"100%\" version=\"1.1\" viewBox=\"0 0 68 48\" width=\"100%\"><path class=\"ytp-large-play-button-bg\" d=\"M66.52,7.74c-0.78-2.93-2.49-5.41-5.42-6.19C55.79,.13,34,0,34,0S12.21,.13,6.9,1.55 C3.97,2.33,2.27,4.81,1.48,7.74C0.06,13.05,0,24,0,24s0.06,10.95,1.48,16.26c0.78,2.93,2.49,5.41,5.42,6.19 C12.21,47.87,34,48,34,48s21.79-0.13,27.1-1.55c2.93-0.78,4.64-3.26,5.42-6.19C67.94,34.95,68,24,68,24S67.94,13.05,66.52,7.74z\" fill=\"#f00\"><\/path><path d=\"M 45,24 27,14 27,34\" fill=\"#fff\"><\/path><\/svg><\/button><\/div><\/div>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;_initial&#8221; custom_margin=&#8221;50px||50px||true|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<blockquote>\n<h3 style=\"text-align: center;\">Cos\u2019\u00e8 la Conoscenza?<br \/>\nNon serve per metterti in contatto con qualcos\u2019altro,<br \/>\nma per metterti in contatto con te stesso.<br \/>\n<\/h3>\n<\/blockquote>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;_initial&#8221; custom_margin=&#8221;-50px||50px||false|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<p style=\"text-align: right;\"><span style=\"font-size: small;\">\u2013 Prem Rawat, Atene, Grecia, 29 giugno 2024<br \/>\n<\/span><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;_initial&#8221; text_font=&#8221;museo-sans|700|||||||&#8221; header_3_font=&#8221;|600|||||||&#8221; header_3_text_color=&#8221;rgba(0,0,0,0.7)&#8221; custom_margin=&#8221;40px||||false|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<h3>Articoli correlati e link<\/h3>\n<p><span style=\"color: #1565b7;\"><a href=\"https:\/\/www.premrawat.com\/tag\/events\/\" style=\"color: #1565b7;\">Eventi <\/a><\/span> \u00a0<span style=\"color: #1565b7;\"><a href=\"https:\/\/www.premrawat.com\/tag\/conoscenza-del-se\/\" style=\"color: #1565b7;\">Conoscenza del S\u00e9<\/a><\/span><span style=\"color: #1565b7;\"> \u00a0<a href=\"https:\/\/www.premrawat.com\/it\/category\/multimedia-it\/\">Multimedia<\/a> <span style=\"color: #1565b7;\"><\/span><span style=\"color: #1565b7;\"><\/span>[\/et_pb_text][dgbc_blog_carousel type=&#8221;3&#8243; include_categories=&#8221;3698,44,3699&#8243; offset_number=&#8221;1&#8243; show_categories=&#8221;off&#8221; show_author=&#8221;off&#8221; show_date=&#8221;off&#8221; show_items_xlarge=&#8221;3&#8243; dot_nav=&#8221;on&#8221; inner_container_padding=&#8221;||||false|false&#8221; content_margin=&#8221;10px||||false|false&#8221; post_content_padding=&#8221;||0px||false|false&#8221; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; header_font_size=&#8221;21px&#8221; header_line_height=&#8221;1.2em&#8221; content_font_size=&#8221;16px&#8221; custom_margin=&#8221;||||false|false&#8221; custom_padding=&#8221;||||false|false&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][\/dgbc_blog_carousel][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nel corso dei mesi di maggio e giugno, Prem Rawat si \u00e8 rivolto a un pubblico riconoscente in cinque citt\u00e0 europee: Dubrovnik in Croazia (19 maggio); Brighton in Inghilterra (8 giugno); Barcellona in Spagna (15 giugno); Roma in Italia (22 giugno) e Atene in Grecia (29 giugno). Sono intervenute dal vivo pi\u00f9 di 5.500 persone, [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":48561,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[4007,4115,4125],"tags":[4229,4253],"podcast-category":[],"class_list":["post-48695","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-conoscenza-del-se","category-eventi-it","category-multimedia-it","tag-personal-peace-it","tag-prem-rawat-it"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il tour europeo 2024 di Prem Rawat - Prem Rawat<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.premrawat.com\/it\/il-tour-europeo-2024-di-prem-rawat\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il tour europeo 2024 di Prem Rawat - Prem Rawat\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.premrawat.com\/it\/il-tour-europeo-2024-di-prem-rawat\/\" \/>\n<meta property=\"og:site_name\" content=\"Prem Rawat\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-02T19:47:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-11T15:08:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.premrawat.com\/wp-content\/uploads\/2024\/08\/European-Tour-Recap-2024-Prem-Rawat-Events.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Premrawat.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Premrawat.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.premrawat.com\\\/it\\\/il-tour-europeo-2024-di-prem-rawat\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.premrawat.com\\\/it\\\/il-tour-europeo-2024-di-prem-rawat\\\/\"},\"author\":{\"name\":\"Premrawat.com\",\"@id\":\"https:\\\/\\\/www.premrawat.com\\\/it\\\/#\\\/schema\\\/person\\\/234f1ca85ac8cb14fc5188673e05c0b1\"},\"headline\":\"Il tour europeo 2024 di Prem Rawat\",\"datePublished\":\"2024-08-02T19:47:04+00:00\",\"dateModified\":\"2024-09-11T15:08:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.premrawat.com\\\/it\\\/il-tour-europeo-2024-di-prem-rawat\\\/\"},\"wordCount\":933,\"publisher\":{\"@id\":\"https:\\\/\\\/www.premrawat.com\\\/it\\\/#\\\/schema\\\/person\\\/234f1ca85ac8cb14fc5188673e05c0b1\"},\"image\":{\"@id\":\"https:\\\/\\\/www.premrawat.com\\\/it\\\/il-tour-europeo-2024-di-prem-rawat\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.premrawat.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/European-Tour-Recap-2024-Prem-Rawat-Events.jpeg\",\"keywords\":[\"personal peace\",\"Prem Rawat\"],\"articleSection\":[\"Conoscenza del S\u00e9\",\"Eventi\",\"Multimedia\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.premrawat.com\\\/it\\\/il-tour-europeo-2024-di-prem-rawat\\\/\",\"url\":\"https:\\\/\\\/www.premrawat.com\\\/it\\\/il-tour-europeo-2024-di-prem-rawat\\\/\",\"name\":\"Il tour europeo 2024 di Prem Rawat - Prem Rawat\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.premrawat.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.premrawat.com\\\/it\\\/il-tour-europeo-2024-di-prem-rawat\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.premrawat.com\\\/it\\\/il-tour-europeo-2024-di-prem-rawat\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.premrawat.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/European-Tour-Recap-2024-Prem-Rawat-Events.jpeg\",\"datePublished\":\"2024-08-02T19:47:04+00:00\",\"dateModified\":\"2024-09-11T15:08:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.premrawat.com\\\/it\\\/il-tour-europeo-2024-di-prem-rawat\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.premrawat.com\\\/it\\\/il-tour-europeo-2024-di-prem-rawat\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.premrawat.com\\\/it\\\/il-tour-europeo-2024-di-prem-rawat\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.premrawat.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/European-Tour-Recap-2024-Prem-Rawat-Events.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.premrawat.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/European-Tour-Recap-2024-Prem-Rawat-Events.jpeg\",\"width\":1200,\"height\":628,\"caption\":\"European- Tour-Recap 2024-Prem Rawat-Events\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.premrawat.com\\\/it\\\/il-tour-europeo-2024-di-prem-rawat\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.premrawat.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il tour europeo 2024 di Prem Rawat\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.premrawat.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.premrawat.com\\\/it\\\/\",\"name\":\"Prem Rawat\",\"description\":\"Peace Educator and Best Selling Author\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.premrawat.com\\\/it\\\/#\\\/schema\\\/person\\\/234f1ca85ac8cb14fc5188673e05c0b1\"},\"alternateName\":\"Premrawat.com\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.premrawat.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.premrawat.com\\\/it\\\/#\\\/schema\\\/person\\\/234f1ca85ac8cb14fc5188673e05c0b1\",\"name\":\"Premrawat.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.premrawat.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/prem-rawat-color-logo1.jpg\",\"url\":\"https:\\\/\\\/www.premrawat.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/prem-rawat-color-logo1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.premrawat.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/prem-rawat-color-logo1.jpg\",\"width\":201,\"height\":202,\"caption\":\"Premrawat.com\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.premrawat.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/prem-rawat-color-logo1.jpg\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il tour europeo 2024 di Prem Rawat - Prem Rawat","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.premrawat.com\/it\/il-tour-europeo-2024-di-prem-rawat\/","og_locale":"it_IT","og_type":"article","og_title":"Il tour europeo 2024 di Prem Rawat - Prem Rawat","og_url":"https:\/\/www.premrawat.com\/it\/il-tour-europeo-2024-di-prem-rawat\/","og_site_name":"Prem Rawat","article_published_time":"2024-08-02T19:47:04+00:00","article_modified_time":"2024-09-11T15:08:07+00:00","og_image":[{"width":1200,"height":628,"url":"https:\/\/www.premrawat.com\/wp-content\/uploads\/2024\/08\/European-Tour-Recap-2024-Prem-Rawat-Events.jpeg","type":"image\/jpeg"}],"author":"Premrawat.com","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Premrawat.com","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.premrawat.com\/it\/il-tour-europeo-2024-di-prem-rawat\/#article","isPartOf":{"@id":"https:\/\/www.premrawat.com\/it\/il-tour-europeo-2024-di-prem-rawat\/"},"author":{"name":"Premrawat.com","@id":"https:\/\/www.premrawat.com\/it\/#\/schema\/person\/234f1ca85ac8cb14fc5188673e05c0b1"},"headline":"Il tour europeo 2024 di Prem Rawat","datePublished":"2024-08-02T19:47:04+00:00","dateModified":"2024-09-11T15:08:07+00:00","mainEntityOfPage":{"@id":"https:\/\/www.premrawat.com\/it\/il-tour-europeo-2024-di-prem-rawat\/"},"wordCount":933,"publisher":{"@id":"https:\/\/www.premrawat.com\/it\/#\/schema\/person\/234f1ca85ac8cb14fc5188673e05c0b1"},"image":{"@id":"https:\/\/www.premrawat.com\/it\/il-tour-europeo-2024-di-prem-rawat\/#primaryimage"},"thumbnailUrl":"https:\/\/www.premrawat.com\/wp-content\/uploads\/2024\/08\/European-Tour-Recap-2024-Prem-Rawat-Events.jpeg","keywords":["personal peace","Prem Rawat"],"articleSection":["Conoscenza del S\u00e9","Eventi","Multimedia"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.premrawat.com\/it\/il-tour-europeo-2024-di-prem-rawat\/","url":"https:\/\/www.premrawat.com\/it\/il-tour-europeo-2024-di-prem-rawat\/","name":"Il tour europeo 2024 di Prem Rawat - Prem Rawat","isPartOf":{"@id":"https:\/\/www.premrawat.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.premrawat.com\/it\/il-tour-europeo-2024-di-prem-rawat\/#primaryimage"},"image":{"@id":"https:\/\/www.premrawat.com\/it\/il-tour-europeo-2024-di-prem-rawat\/#primaryimage"},"thumbnailUrl":"https:\/\/www.premrawat.com\/wp-content\/uploads\/2024\/08\/European-Tour-Recap-2024-Prem-Rawat-Events.jpeg","datePublished":"2024-08-02T19:47:04+00:00","dateModified":"2024-09-11T15:08:07+00:00","breadcrumb":{"@id":"https:\/\/www.premrawat.com\/it\/il-tour-europeo-2024-di-prem-rawat\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.premrawat.com\/it\/il-tour-europeo-2024-di-prem-rawat\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.premrawat.com\/it\/il-tour-europeo-2024-di-prem-rawat\/#primaryimage","url":"https:\/\/www.premrawat.com\/wp-content\/uploads\/2024\/08\/European-Tour-Recap-2024-Prem-Rawat-Events.jpeg","contentUrl":"https:\/\/www.premrawat.com\/wp-content\/uploads\/2024\/08\/European-Tour-Recap-2024-Prem-Rawat-Events.jpeg","width":1200,"height":628,"caption":"European- Tour-Recap 2024-Prem Rawat-Events"},{"@type":"BreadcrumbList","@id":"https:\/\/www.premrawat.com\/it\/il-tour-europeo-2024-di-prem-rawat\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.premrawat.com\/it\/"},{"@type":"ListItem","position":2,"name":"Il tour europeo 2024 di Prem Rawat"}]},{"@type":"WebSite","@id":"https:\/\/www.premrawat.com\/it\/#website","url":"https:\/\/www.premrawat.com\/it\/","name":"Prem Rawat","description":"Peace Educator and Best Selling Author","publisher":{"@id":"https:\/\/www.premrawat.com\/it\/#\/schema\/person\/234f1ca85ac8cb14fc5188673e05c0b1"},"alternateName":"Premrawat.com","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.premrawat.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Person","Organization"],"@id":"https:\/\/www.premrawat.com\/it\/#\/schema\/person\/234f1ca85ac8cb14fc5188673e05c0b1","name":"Premrawat.com","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.premrawat.com\/wp-content\/uploads\/2024\/01\/prem-rawat-color-logo1.jpg","url":"https:\/\/www.premrawat.com\/wp-content\/uploads\/2024\/01\/prem-rawat-color-logo1.jpg","contentUrl":"https:\/\/www.premrawat.com\/wp-content\/uploads\/2024\/01\/prem-rawat-color-logo1.jpg","width":201,"height":202,"caption":"Premrawat.com"},"logo":{"@id":"https:\/\/www.premrawat.com\/wp-content\/uploads\/2024\/01\/prem-rawat-color-logo1.jpg"}}]}},"_links":{"self":[{"href":"https:\/\/www.premrawat.com\/it\/wp-json\/wp\/v2\/posts\/48695","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.premrawat.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.premrawat.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.premrawat.com\/it\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.premrawat.com\/it\/wp-json\/wp\/v2\/comments?post=48695"}],"version-history":[{"count":9,"href":"https:\/\/www.premrawat.com\/it\/wp-json\/wp\/v2\/posts\/48695\/revisions"}],"predecessor-version":[{"id":49171,"href":"https:\/\/www.premrawat.com\/it\/wp-json\/wp\/v2\/posts\/48695\/revisions\/49171"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.premrawat.com\/it\/wp-json\/wp\/v2\/media\/48561"}],"wp:attachment":[{"href":"https:\/\/www.premrawat.com\/it\/wp-json\/wp\/v2\/media?parent=48695"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.premrawat.com\/it\/wp-json\/wp\/v2\/categories?post=48695"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.premrawat.com\/it\/wp-json\/wp\/v2\/tags?post=48695"},{"taxonomy":"podcast-category","embeddable":true,"href":"https:\/\/www.premrawat.com\/it\/wp-json\/wp\/v2\/podcast-category?post=48695"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}